{"id":19,"date":"2026-07-12T19:22:48","date_gmt":"2026-07-12T13:52:48","guid":{"rendered":"https:\/\/samajsanwad.com\/author-profile\/"},"modified":"2026-07-12T19:22:48","modified_gmt":"2026-07-12T13:52:48","slug":"author-profile","status":"publish","type":"page","link":"https:\/\/samajsanwad.com\/en_gb\/author-profile\/","title":{"rendered":"Author Profile"},"content":{"rendered":"<section class=\"directory_wrapper single_area\">\n                    <div class=\"notice_wrapper\">\n                        <div class=\"directorist-alert directorist-alert-warning\">\n                            <i class=\"directorist-icon-mask\" aria-hidden=\"true\" style=\"--directorist-icon: url(https:\/\/samajsanwad.com\/wp-content\/plugins\/directorist\/assets\/icons\/line-awesome\/svgs\/info-circle-solid.svg)\"><\/i>                            Nothing to show!                        <\/div>\n                    <\/div>\n                <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_rtcl_gb_attr":"","footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"shantanujoshi400@gmail.com","author_link":"https:\/\/samajsanwad.com\/en_gb\/author\/shantanujoshi400gmail-com\/"},"rttpg_comment":0,"rttpg_category":null,"rttpg_excerpt":null,"_links":{"self":[{"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":0,"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"wp:attachment":[{"href":"https:\/\/samajsanwad.com\/en_gb\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}